{"id":12240,"date":"2016-08-24T17:03:25","date_gmt":"2016-08-24T08:03:25","guid":{"rendered":"http:\/\/www.polymer-glasscoating.com\/blog\/?p=12240"},"modified":"2018-02-15T21:46:51","modified_gmt":"2018-02-15T12:46:51","slug":"%e3%83%9b%e3%83%b3%e3%83%80%ef%bd%93660","status":"publish","type":"post","link":"https:\/\/www.polymer-glasscoating.com\/blog\/work_type\/result\/%e3%83%9b%e3%83%b3%e3%83%80%ef%bd%93660\/","title":{"rendered":"\u30db\u30f3\u30c0\uff33660"},"content":{"rendered":"<p><a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05fc0f46.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12241 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05fc0f46.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05fc0f46.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05fc0f46-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05ecd49f.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12242 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05ecd49f.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05ecd49f.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/05ecd49f-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/07b7a664.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12243 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/07b7a664.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/07b7a664.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/07b7a664-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f2263a91.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12244 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f2263a91.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f2263a91.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f2263a91-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8ded9b4b.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12245 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8ded9b4b.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8ded9b4b.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8ded9b4b-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/84fbb7c1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12246 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/84fbb7c1.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/84fbb7c1.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/84fbb7c1-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f8bdfd52.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12247 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f8bdfd52.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f8bdfd52.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/f8bdfd52-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/c527c63f.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12248 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/c527c63f.jpg\" alt=\"\" width=\"647\" height=\"429\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/c527c63f.jpg 647w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/c527c63f-300x199.jpg 300w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":12241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,240,199,198],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts\/12240"}],"collection":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/comments?post=12240"}],"version-history":[{"count":3,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts\/12240\/revisions"}],"predecessor-version":[{"id":17766,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts\/12240\/revisions\/17766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/media\/12241"}],"wp:attachment":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/media?parent=12240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/categories?post=12240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/tags?post=12240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}