{"id":1699,"date":"2016-10-19T14:05:51","date_gmt":"2016-10-19T05:05:51","guid":{"rendered":"http:\/\/www.polymer-glasscoating.com\/blog\/?p=1699"},"modified":"2018-04-07T15:53:45","modified_gmt":"2018-04-07T06:53:45","slug":"%e3%83%a1%e3%83%ab%e3%82%bb%e3%83%87%e3%82%b9%e3%83%99%e3%83%b3%e3%83%84c180","status":"publish","type":"post","link":"https:\/\/www.polymer-glasscoating.com\/blog\/work_type\/result\/%e3%83%a1%e3%83%ab%e3%82%bb%e3%83%87%e3%82%b9%e3%83%99%e3%83%b3%e3%83%84c180\/","title":{"rendered":"\u30e1\u30eb\u30bb\u30c7\u30b9\u30d9\u30f3\u30c4C180"},"content":{"rendered":"<p><a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8728092d1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1700 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8728092d1.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8728092d1.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8728092d1-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/8728092d1-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/19b2aef81.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1706 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/19b2aef81.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/19b2aef81.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/19b2aef81-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/19b2aef81-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/1eaf9a841.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1702 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/1eaf9a841.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/1eaf9a841.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/1eaf9a841-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/1eaf9a841-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/b7fcdf761.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1701 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/b7fcdf761.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/b7fcdf761.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/b7fcdf761-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/b7fcdf761-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/565a534a1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1708 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/565a534a1.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/565a534a1.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/565a534a1-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/565a534a1-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/3d27b7b01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1703 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/3d27b7b01.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/3d27b7b01.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/3d27b7b01-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/3d27b7b01-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/85c1a3481.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1707 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/85c1a3481.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/85c1a3481.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/85c1a3481-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/85c1a3481-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/9c9f197f1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1705 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/9c9f197f1.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/9c9f197f1.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/9c9f197f1-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/9c9f197f1-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/7a7fd1811.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1704 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/7a7fd1811.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/7a7fd1811.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/7a7fd1811-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/7a7fd1811-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a> <a href=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/083588fe1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1709 size-full\" src=\"http:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/083588fe1.jpg\" alt=\"\" width=\"840\" height=\"557\" srcset=\"https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/083588fe1.jpg 840w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/083588fe1-300x199.jpg 300w, https:\/\/www.polymer-glasscoating.com\/blog\/wp-content\/uploads\/083588fe1-768x509.jpg 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,200],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts\/1699"}],"collection":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/comments?post=1699"}],"version-history":[{"count":3,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts\/1699\/revisions"}],"predecessor-version":[{"id":19911,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/posts\/1699\/revisions\/19911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/media\/1706"}],"wp:attachment":[{"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/media?parent=1699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/categories?post=1699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polymer-glasscoating.com\/blog\/wp-json\/wp\/v2\/tags?post=1699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}